{"id":1135,"date":"2023-07-20T12:37:12","date_gmt":"2023-07-20T12:37:12","guid":{"rendered":"https:\/\/wp.ull.es\/vicmovi\/?p=1135"},"modified":"2023-07-20T12:51:34","modified_gmt":"2023-07-20T12:51:34","slug":"desino-warsaw-university-of-technology-polonia","status":"publish","type":"post","link":"https:\/\/wp.ull.es\/vicmovi\/2023\/07\/20\/desino-warsaw-university-of-technology-polonia\/","title":{"rendered":"Destino: Warsaw University of Technology, Polonia"},"content":{"rendered":"\n<p>Samuel Medina Hern\u00e1ndez del grado de ADE, nos cuenta su experiencia en \u00abWarsaw University of Technology, Polonia\u00bb, vivida durante el curso 2022\/23:<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"480\" height=\"640\" data-id=\"1136\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image9.jpeg\" alt=\"\" class=\"wp-image-1136\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image9.jpeg 480w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image9-225x300.jpeg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"640\" height=\"480\" data-id=\"1137\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image3.jpeg\" alt=\"\" class=\"wp-image-1137\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image3.jpeg 640w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image3-300x225.jpeg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"480\" height=\"640\" data-id=\"1138\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image2.jpeg\" alt=\"\" class=\"wp-image-1138\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image2.jpeg 480w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image2-225x300.jpeg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"480\" height=\"640\" data-id=\"1139\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image0.jpeg\" alt=\"\" class=\"wp-image-1139\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image0.jpeg 480w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image0-225x300.jpeg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"480\" height=\"640\" data-id=\"1140\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image1.jpeg\" alt=\"\" class=\"wp-image-1140\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image1.jpeg 480w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image1-225x300.jpeg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"480\" height=\"640\" data-id=\"1141\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image6.jpeg\" alt=\"\" class=\"wp-image-1141\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image6.jpeg 480w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/image6-225x300.jpeg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>1 &#8211; \u00bfPor qu\u00e9 decidiste hacer un Erasmus?<\/p>\n\n\n\n<p>Por tener una experiencia diferente a la monoton\u00eda de siempre y de cara al futuro tambi\u00e9n te hace madurar el hecho de irte solo a un pa\u00eds que no conoces, con gente de todo los pa\u00edses y aprender ingl\u00e9s.<\/p>\n\n\n\n<p>2 &#8211; \u00bfPor qu\u00e9 elegiste ese destino?<\/p>\n\n\n\n<p>Por ir a un pa\u00eds m\u00e1s diferente y m\u00e1s lejano, del este ,con condiciones muy diferentes a lo que hay aqu\u00ed como la manera de vida, el clima. Algo que requiere una adaptaci\u00f3n y porque se supone que era un poco m\u00e1s barato que aqu\u00ed.&nbsp;<\/p>\n\n\n\n<p>3 &#8211; \u00bfEn qu\u00e9 periodo te fuiste?<\/p>\n\n\n\n<p>El curso completo desde septiembre hasta junio.<\/p>\n\n\n\n<p>4 &#8211; \u00bfC\u00f3mo fue tu llegada a la instituci\u00f3n de destino?<\/p>\n\n\n\n<p>Bien, hacen un primer d\u00eda con los alumnos de presentaci\u00f3n, explic\u00e1ndote c\u00f3mo van a ser las clases.&nbsp; Te ayudan con esa reuni\u00f3n y despu\u00e9s te dan contactos de email y dem\u00e1s para poder preguntar dudas.<\/p>\n\n\n\n<p>5 &#8211; \u00bfC\u00f3mo encontraste alojamiento?<\/p>\n\n\n\n<p>Residencia de la universidad. No tuve ning\u00fan problema, fue super r\u00e1pido. Me informaron de c\u00f3mo pod\u00eda solicitar la residencia, lo hice y me la aceptaron.&nbsp;<\/p>\n\n\n\n<p>6 &#8211; \u00bfLa organizaci\u00f3n de las clases es diferente a Espa\u00f1a?<\/p>\n\n\n\n<p>Si, alli un dia tenias clase, un dia no tenias nada, con el horario cambiante. Las clases duran diferentes horas, es mucho m\u00e1s cambiante.<\/p>\n\n\n\n<p>7 &#8211; \u00bfC\u00f3mo se organizaban all\u00ed los ex\u00e1menes?&nbsp;<\/p>\n\n\n\n<p>Realmente, parecido a aqu\u00ed. El profesor te daba la fecha del test, la mayor\u00eda era mediante ordenador e ibas a pasar el examen. No hab\u00eda muchos porque la mayor\u00eda de las clases se evaluaban por presentaciones, trabajos y los test tuve muy poco contados.&nbsp;<\/p>\n\n\n\n<p>8 &#8211; \u00bfTe sentiste integrado en la universidad?<\/p>\n\n\n\n<p>Nivel medio, si bien. No me sent\u00ed mal en el sentido de sentirme solo.&nbsp;<\/p>\n\n\n\n<p>9 &#8211; \u00bfQu\u00e9 aspectos de tu movilidad crees que te han marcado m\u00e1s?&nbsp;<\/p>\n\n\n\n<p>La gente que he conocido, el hecho de tener que defenderte en ingl\u00e9s en un pa\u00eds que no conoces,el hecho de vivir solo. Viv\u00eda en la residencia en una habitaci\u00f3n compartida con un turco, tambi\u00e9n te hace ver las cosas de otra manera.&nbsp;<\/p>\n\n\n\n<p>10 &#8211; \u00bfHab\u00eda muchos estudiantes de Erasmus en tu ciudad de destino?<\/p>\n\n\n\n<p>Si, bastante.<\/p>\n\n\n\n<p>11 &#8211; \u00bfExist\u00eda una organizaci\u00f3n Erasmus all\u00ed en la que poder apoyarte?&nbsp;<\/p>\n\n\n\n<p>Hab\u00eda una oficina dedicada solo al Erasmus y te ayudaba mucho. Tambi\u00e9n hab\u00eda la ESN.<\/p>\n\n\n\n<p>12 &#8211; \u00bfQu\u00e9 piensas de la ciudad en la que estuviste?<\/p>\n\n\n\n<p>Me gust\u00f3 mucho, la recomiendo salvo por el clima pero bueno eso es adaptarse, muy buena ciudad muy recomendable para el erasmus. Estas cerca de muchos pa\u00edses entonces a la hora de viajar es muy barato muy f\u00e1cil. Tiene muy buena conectividad mediante trenes. En la ciudad el transporte p\u00fablico est\u00e1 muy bien, los precios no son muy elevados.&nbsp;<\/p>\n\n\n\n<p>13 &#8211; \u00bfCu\u00e1l era tu nivel de idiomas antes de irte?<\/p>\n\n\n\n<p>Un B2 de ingl\u00e9s.<\/p>\n\n\n\n<p>14 &#8211; \u00bfQu\u00e9 nivel de idiomas alcanzaste al final de tu estancia?<\/p>\n\n\n\n<p>Ha mejorado, no s\u00e9 si para un C1. Sobre todo la fluidez a la hora de hablar porque al principio no lo entiendes todo y al final lo vas entendiendo mejor.&nbsp;&nbsp;<\/p>\n\n\n\n<p>15 &#8211; \u00bfCu\u00e1les son los beneficios que sacas de esta experiencia?<\/p>\n\n\n\n<p>Much\u00edsimos: el hecho de que manera ves las cosas despu\u00e9s de hacerlo, valoras mucho m\u00e1s las cosas, todo lo que has dejado en tu lugar. Tambi\u00e9n te das cuenta de todo lo que hay fuera, de todo lo que puedes aprender de otras personas, viajas much\u00edsimo, conoces ciudades que no habr\u00edas visitado si no te vas de erasmus, mucha fiesta tambi\u00e9n.Casi siempre estas haciendo cosas porque al final siempre te est\u00e1s moviendo.&nbsp;<\/p>\n\n\n\n<p>16 &#8211; \u00bfQu\u00e9 consejos le podr\u00edas dar a una persona que se va de Erasmus al mismo sitio?<\/p>\n\n\n\n<p>En primer lugar que no lo piense, vete porque no te vas a arrepentir, que intente siempre ser una persona muy abierta a conocer gente, eso me cuesta pero si estas muy abierto vas a estar muy bien all\u00ed porque vas a estar continuamente relacion\u00e1ndote con personas. Inf\u00f3rmate sobre el pa\u00eds, la ciudad de Varsovia, como es la vida all\u00ed y c\u00f3mo funciona, la universidad tambi\u00e9n. El ir all\u00ed es un poco ir a la aventura pero est\u00e1 bien.<\/p>\n\n\n\n<p>Si quieres mas informaciones, puedes contactar a Samuel Medina Hern\u00e1ndez: &nbsp;<a href=\"mailto:alu0101415277@ull.edu.es\">alu0101415277@ull.edu.es<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Samuel Medina Hern\u00e1ndez del grado de ADE, nos cuenta su experiencia en \u00abWarsaw University of Technology, Polonia\u00bb, vivida durante el curso 2022\/23: 1 &#8211; \u00bfPor qu\u00e9 decidiste hacer un Erasmus? Por tener una experiencia diferente a la monoton\u00eda de siempre y de cara al futuro tambi\u00e9n te hace madurar el hecho de irte solo a &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/wp.ull.es\/vicmovi\/2023\/07\/20\/desino-warsaw-university-of-technology-polonia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDestino: Warsaw University of Technology, Polonia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":368,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1135","post","type-post","status-publish","format-standard","hentry","category-erasmus"],"_links":{"self":[{"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/posts\/1135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/users\/368"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/comments?post=1135"}],"version-history":[{"count":2,"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/posts\/1135\/revisions"}],"predecessor-version":[{"id":1145,"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/posts\/1135\/revisions\/1145"}],"wp:attachment":[{"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/media?parent=1135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/categories?post=1135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/tags?post=1135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}