{"id":1124,"date":"2023-07-20T12:28:26","date_gmt":"2023-07-20T12:28:26","guid":{"rendered":"https:\/\/wp.ull.es\/vicmovi\/?p=1124"},"modified":"2023-07-25T11:24:14","modified_gmt":"2023-07-25T11:24:14","slug":"destino-alma-mater-studiorum-universita-di-bologna-italia","status":"publish","type":"post","link":"https:\/\/wp.ull.es\/vicmovi\/2023\/07\/20\/destino-alma-mater-studiorum-universita-di-bologna-italia\/","title":{"rendered":"Destino: Alma Mater Studiorum-Universit\u00e1 Di Bologna, Italia"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"997\" height=\"1024\" data-id=\"1166\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164520-997x1024.jpg\" alt=\"\" class=\"wp-image-1166\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164520-997x1024.jpg 997w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164520-292x300.jpg 292w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164520-768x789.jpg 768w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164520.jpg 1080w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"797\" height=\"1024\" data-id=\"1167\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164508-797x1024.jpg\" alt=\"\" class=\"wp-image-1167\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164508-797x1024.jpg 797w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164508-234x300.jpg 234w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164508-768x986.jpg 768w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164508.jpg 1080w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"1127\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_0196-576x1024.jpeg\" alt=\"\" class=\"wp-image-1127\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_0196-576x1024.jpeg 576w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_0196-169x300.jpeg 169w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_0196-768x1365.jpeg 768w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_0196-864x1536.jpeg 864w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_0196.jpeg 900w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"1169\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_20230722_002114-768x1024.jpg\" alt=\"\" class=\"wp-image-1169\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_20230722_002114-768x1024.jpg 768w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_20230722_002114-225x300.jpg 225w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_20230722_002114-1152x1536.jpg 1152w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_20230722_002114.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"758\" data-id=\"1168\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164543-1024x758.jpg\" alt=\"\" class=\"wp-image-1168\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164543-1024x758.jpg 1024w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164543-300x222.jpg 300w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164543-768x568.jpg 768w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164543.jpg 1080w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"789\" height=\"1024\" data-id=\"1170\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164533-789x1024.jpg\" alt=\"\" class=\"wp-image-1170\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164533-789x1024.jpg 789w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164533-231x300.jpg 231w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164533-768x996.jpg 768w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164533.jpg 1080w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>&nbsp;Amanda Audelina Gonz\u00e1lez Valladares del grado de Turismo, nos cuenta su experiencia en \u00abAlma Mater Studiorum-Universit\u00e1 Di Bologna\u00bb, vivida durante el curso 2022\/23:<\/p>\n\n\n\n<p>1 &#8211; \u00bfPor qu\u00e9 decidiste hacer un Erasmus?<\/p>\n\n\n\n<p>Porque me gusta el lugar donde vivo pero siempre he querido conocer un poco m\u00e1s y sobre todo estar en Europa, para viajar es m\u00e1s f\u00e1cil, conoces a gente y me encanta el italiano.<\/p>\n\n\n\n<p>2 &#8211; \u00bfPor qu\u00e9 elegiste ese destino?<\/p>\n\n\n\n<p>Solo hab\u00eda 2 en Italia, era el que m\u00e1s me gustaba porque es la ciudad m\u00e1s universitaria. Aunque despu\u00e9s nos dimos cuenta de que era en Rimini y no en Bologna, pero aun as\u00ed me encant\u00f3.<\/p>\n\n\n\n<p>3 &#8211; \u00bfEn qu\u00e9 periodo te fuiste?<\/p>\n\n\n\n<p>De septiembre de 2022 hasta junio 2023.<\/p>\n\n\n\n<p>4 &#8211; \u00bfC\u00f3mo fue tu llegada a la instituci\u00f3n de destino?<\/p>\n\n\n\n<p>Bastante bien, los profesores fueron super buenos, intentaban ayudarte y la verdad que fue nada dif\u00edcil la adaptaci\u00f3n.<\/p>\n\n\n\n<p>5 &#8211; \u00bfC\u00f3mo encontraste alojamiento?<\/p>\n\n\n\n<p>En las dos \u00faltimas semanas, solo fue para un par de d\u00edas y luego cuando llegamos all\u00ed nos dedicamos a buscar para todo el a\u00f1o y fue un poco complicado.&nbsp;&nbsp;<\/p>\n\n\n\n<p>6 &#8211; \u00bfLa organizaci\u00f3n de las clases es diferente a Espa\u00f1a?<\/p>\n\n\n\n<p>Si, las clases son de 3 horas, a veces puede ser pesado porque a lo mejor hab\u00eda un d\u00eda que ten\u00edamos tres clases y entonces ten\u00edamos 9 horas de clase.<\/p>\n\n\n\n<p>7 &#8211; \u00bfC\u00f3mo se organizaban all\u00ed los ex\u00e1menes?&nbsp;<\/p>\n\n\n\n<p>Super parecido a aqu\u00ed, ya que ten\u00edamos parciales en todo el curso en determinadas asignaturas y luego los ex\u00e1menes finales. Algunas asignaturas te las pod\u00edas quitar haciendo trabajos o con los ex\u00e1menes, parciales y no ten\u00edas que hacer examen final.&nbsp;<\/p>\n\n\n\n<p>8 &#8211; \u00bfTe sentiste integrada en la universidad?<\/p>\n\n\n\n<p>Si, fui con amigos y soy una persona sociable me he adaptado bien, conoc\u00ed nuevas personas tanto italianos como de erasmus.<\/p>\n\n\n\n<p>9 &#8211; \u00bfQu\u00e9 aspectos de tu movilidad crees que te han marcado m\u00e1s?&nbsp;<\/p>\n\n\n\n<p>La gente que he conocido, porque formas relaciones de amistad que se quedan all\u00ed al recuerdo y la forma en la que vives la universidad al estar en otro pa\u00eds sabiendo que es una experiencia corta intentas aprovechar un m\u00e1ximo.&nbsp;&nbsp;<\/p>\n\n\n\n<p>10 &#8211; \u00bfHab\u00eda muchos estudiantes de Erasmus en tu ciudad de destino?<\/p>\n\n\n\n<p>Si, bastante.<\/p>\n\n\n\n<p>11 &#8211; \u00bfExist\u00eda una organizaci\u00f3n Erasmus all\u00ed en la que poder apoyarte?&nbsp;<\/p>\n\n\n\n<p>Si, la ESN Rimini.&nbsp;<\/p>\n\n\n\n<p>12 &#8211; \u00bfQu\u00e9 piensas de la ciudad en la que estuviste?<\/p>\n\n\n\n<p>Vivir all\u00ed, no vivir\u00eda, pero la \u00e9poca de abril a septiembre es la mejor \u00e9poca porque siempre hay planes que hacer. En invierno es un poco m\u00e1s aburrido aunque si conoces gente pues es m\u00e1s f\u00e1cil hacer planes.&nbsp;&nbsp;<\/p>\n\n\n\n<p>13 &#8211; \u00bfCu\u00e1l era tu nivel de idiomas antes de irte?<\/p>\n\n\n\n<p>Ten\u00eda un B1 ingl\u00e9s y no ten\u00eda nivel de italiano aunque lo entend\u00eda un poco.&nbsp;<\/p>\n\n\n\n<p>14 &#8211; \u00bfQu\u00e9 nivel de idiomas alcanzaste al final de tu estancia?<\/p>\n\n\n\n<p>Tengo B1 de ingl\u00e9s &amp; italiano.<\/p>\n\n\n\n<p>15 &#8211; \u00bfCu\u00e1les son los beneficios que sacas de esta experiencia?<\/p>\n\n\n\n<p>Las nuevas amistades, tambi\u00e9n nuevos conocimientos y nuevas formas de ver el mundo porque al estar en una isla aqu\u00ed tambi\u00e9n es un poco m\u00e1s cerrado solo conoces esto entonces es como abrirse a conocer m\u00e1s. Tambi\u00e9n sitios en general porque es mucho m\u00e1s f\u00e1cil y m\u00e1s barato viajar desde all\u00ed.&nbsp;<\/p>\n\n\n\n<p>16 &#8211; \u00bfQu\u00e9 consejos le podr\u00edas dar a una persona que se va de Erasmus al mismo sitio?<\/p>\n\n\n\n<p>Que busque el alojamiento con mucha antelaci\u00f3n, que tenga en cuenta la seguridad, es una ciudad un poco peligrosa depende de qu\u00e9 zona. Que se la pase bien en verano que es la mejor \u00e9poca.&nbsp;<\/p>\n\n\n\n<p>Si quieres mas informaciones o dudas, puedes contactar a Amanda Audelina Gonz\u00e1lez Valladares: <a href=\"mailto:alu0101400204@ull.edu.es\">alu0101400204@ull.edu.es<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"1172\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_20230717_164831.jpg\" alt=\"\" class=\"wp-image-1172\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_20230717_164831.jpg 768w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_20230717_164831-225x300.jpg 225w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"1173\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_20230717_164454.jpg\" alt=\"\" class=\"wp-image-1173\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_20230717_164454.jpg 768w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/IMG_20230717_164454-225x300.jpg 225w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"827\" height=\"1024\" data-id=\"1174\" src=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164600-827x1024.jpg\" alt=\"\" class=\"wp-image-1174\" srcset=\"https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164600-827x1024.jpg 827w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164600-242x300.jpg 242w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164600-768x951.jpg 768w, https:\/\/wp.ull.es\/vicmovi\/wp-content\/uploads\/sites\/142\/2023\/07\/Screenshot_20230717_164600.jpg 1080w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;Amanda Audelina Gonz\u00e1lez Valladares del grado de Turismo, nos cuenta su experiencia en \u00abAlma Mater Studiorum-Universit\u00e1 Di Bologna\u00bb, vivida durante el curso 2022\/23: 1 &#8211; \u00bfPor qu\u00e9 decidiste hacer un Erasmus? Porque me gusta el lugar donde vivo pero siempre he querido conocer un poco m\u00e1s y sobre todo estar en Europa, para viajar es &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/wp.ull.es\/vicmovi\/2023\/07\/20\/destino-alma-mater-studiorum-universita-di-bologna-italia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDestino: Alma Mater Studiorum-Universit\u00e1 Di Bologna, Italia\u00bb<\/span><\/a><\/p>\n","protected":false},"author":368,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1124","post","type-post","status-publish","format-standard","hentry","category-erasmus"],"_links":{"self":[{"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/posts\/1124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/users\/368"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/comments?post=1124"}],"version-history":[{"count":2,"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/posts\/1124\/revisions"}],"predecessor-version":[{"id":1175,"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/posts\/1124\/revisions\/1175"}],"wp:attachment":[{"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/media?parent=1124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/categories?post=1124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ull.es\/vicmovi\/wp-json\/wp\/v2\/tags?post=1124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}