{"id":5505,"date":"2024-04-18T15:29:09","date_gmt":"2024-04-18T15:29:09","guid":{"rendered":"https:\/\/wp.ull.es\/aenogas\/?p=5505"},"modified":"2024-04-18T15:29:11","modified_gmt":"2024-04-18T15:29:11","slug":"el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna","status":"publish","type":"post","link":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/","title":{"rendered":"El enoturismo en la 38 Semana de la Empresa de la Facultad de Econom\u00eda de la Universidad de La Laguna"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La C\u00e1tedra de Agroturismo y Enoturismo de Canarias del Instituto Canario de Calidad Agroalimentaria y de la Universidad de La Laguna, particip\u00f3 en la 38 Semana de la Empresa promovida por la Delegaci\u00f3n de Estudiantes, de la Facultad de Econom\u00eda, Empresa y Turismo de la instituci\u00f3n acad\u00e9mica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acto tuvo lugar hoy, en el sala de juntas de la facultad, contando con la participaci\u00f3n de Isaac Mart\u00edn Mendoza, investigador alumno de grado de Geograf\u00eda y Ordenaci\u00f3n del Territorio junto con Francisco Borja de Mesa Manrique, vicepresidente del Cl\u00faster de Enoturismo de Canarias y gerente de Bodegas El Lomo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mart\u00edn expuso ante el alumnado asistente los resultados de la monitorizaci\u00f3n del enoturismo en las islas Canarias, un informe que desvela los primeros datos de la actividad tur\u00edstica del archipi\u00e9lago desde la perspectiva empresarial de las bodegas participantes. A continuaci\u00f3n Mesa imparte la sesi\u00f3n que llevaba por t\u00edtulo \u201cLa revoluci\u00f3n necesaria desde el terroir al mercado del turismo internacional\u201d, con el objetivo de dar a conocer la importancia de la actividad enotur\u00edstica para el sector vitivin\u00edcola canario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acto adem\u00e1s cont\u00f3 con la presencia del subdirector de la C\u00e1tedra de Agroturismo y Enoturismo de Canarias, Gabriel Santos Garc\u00eda y del presidente del Cl\u00faster de Enoturismo de Canarias, Jos\u00e9 Maria G\u00f3mez Medina, que agradecieron la invitaci\u00f3n de participar en la Semana de la Empresa un evento que alberga en esta edici\u00f3n el descubrimiento de destinos sostenibles. Y que en palabras del subdirector de la C\u00e1tedra acerca la sociedad y en esta ocasi\u00f3n la realidad empresarial al alumnado universitario, facilitando el conocer nuevas salidas profesionales o l\u00edneas donde emprender.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"685\" data-id=\"5507\" src=\"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-5.jpg\" alt=\"\" class=\"wp-image-5507\" srcset=\"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-5.jpg 1024w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-5-300x201.jpg 300w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-5-768x514.jpg 768w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-5-100x67.jpg 100w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-5-150x100.jpg 150w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-5-200x134.jpg 200w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-5-450x301.jpg 450w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-5-600x401.jpg 600w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-5-900x602.jpg 900w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"685\" data-id=\"5508\" src=\"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-3.jpg\" alt=\"\" class=\"wp-image-5508\" srcset=\"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-3.jpg 1024w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-3-300x201.jpg 300w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-3-768x514.jpg 768w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-3-100x67.jpg 100w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-3-150x100.jpg 150w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-3-200x134.jpg 200w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-3-450x301.jpg 450w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-3-600x401.jpg 600w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-3-900x602.jpg 900w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"685\" data-id=\"5509\" src=\"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-4.jpg\" alt=\"\" class=\"wp-image-5509\" srcset=\"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-4.jpg 1024w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-4-300x201.jpg 300w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-4-768x514.jpg 768w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-4-100x67.jpg 100w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-4-150x100.jpg 150w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-4-200x134.jpg 200w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-4-450x301.jpg 450w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-4-600x401.jpg 600w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Borja-de-Mesa-4-900x602.jpg 900w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"685\" data-id=\"5510\" src=\"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-4.jpg\" alt=\"\" class=\"wp-image-5510\" srcset=\"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-4.jpg 1024w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-4-300x201.jpg 300w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-4-768x514.jpg 768w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-4-100x67.jpg 100w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-4-150x100.jpg 150w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-4-200x134.jpg 200w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-4-450x301.jpg 450w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-4-600x401.jpg 600w, https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-4-900x602.jpg 900w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La C\u00e1tedra de Agroturismo y Enoturismo de Canarias del Instituto Canario de Calidad Agroalimentaria y de la Universidad de La Laguna, particip\u00f3 en la 38 Semana de la Empresa promovida por la Delegaci\u00f3n de Estudiantes, de la Facultad de Econom\u00eda, Empresa y Turismo de la instituci\u00f3n acad\u00e9mica.<\/p>\n<div class=\"read-more\"><a href=\"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/\">Leer m\u00e1s \u203a<\/a><\/div>\n<p><!-- end of .read-more --><\/p>\n","protected":false},"author":227,"featured_media":5506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,1],"tags":[7,6],"class_list":["post-5505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-sin-categoria","tag-enoturismo","tag-universidad-de-la-laguna"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El enoturismo en la 38 Semana de la Empresa de la Facultad de Econom\u00eda de la Universidad de La Laguna - Enoturismo Canarias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El enoturismo en la 38 Semana de la Empresa de la Facultad de Econom\u00eda de la Universidad de La Laguna - Enoturismo Canarias\" \/>\n<meta property=\"og:description\" content=\"La C\u00e1tedra de Agroturismo y Enoturismo de Canarias del Instituto Canario de Calidad Agroalimentaria y de la Universidad de La Laguna, particip\u00f3 en la 38 Semana de la Empresa promovida por la Delegaci\u00f3n de Estudiantes, de la Facultad de Econom\u00eda, Empresa y Turismo de la instituci\u00f3n acad\u00e9mica.Leer m\u00e1s \u203a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/\" \/>\n<meta property=\"og:site_name\" content=\"Enoturismo Canarias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/enoturismoull\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-18T15:29:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T15:29:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"685\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aenogas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@enoturismoull\" \/>\n<meta name=\"twitter:site\" content=\"@enoturismoull\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aenogas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/2024\\\/04\\\/18\\\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/2024\\\/04\\\/18\\\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\\\/\"},\"author\":{\"name\":\"aenogas\",\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/#\\\/schema\\\/person\\\/08dc3be5406aba55875ae5024a8e7426\"},\"headline\":\"El enoturismo en la 38 Semana de la Empresa de la Facultad de Econom\u00eda de la Universidad de La Laguna\",\"datePublished\":\"2024-04-18T15:29:09+00:00\",\"dateModified\":\"2024-04-18T15:29:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/2024\\\/04\\\/18\\\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\\\/\"},\"wordCount\":315,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/2024\\\/04\\\/18\\\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/wp-content\\\/uploads\\\/sites\\\/90\\\/2024\\\/04\\\/Semana-6.jpg\",\"keywords\":[\"enoturismo\",\"universidad de la laguna\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/2024\\\/04\\\/18\\\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/2024\\\/04\\\/18\\\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\\\/\",\"url\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/2024\\\/04\\\/18\\\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\\\/\",\"name\":\"El enoturismo en la 38 Semana de la Empresa de la Facultad de Econom\u00eda de la Universidad de La Laguna - Enoturismo Canarias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/2024\\\/04\\\/18\\\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/2024\\\/04\\\/18\\\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/wp-content\\\/uploads\\\/sites\\\/90\\\/2024\\\/04\\\/Semana-6.jpg\",\"datePublished\":\"2024-04-18T15:29:09+00:00\",\"dateModified\":\"2024-04-18T15:29:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/2024\\\/04\\\/18\\\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/2024\\\/04\\\/18\\\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/2024\\\/04\\\/18\\\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/wp-content\\\/uploads\\\/sites\\\/90\\\/2024\\\/04\\\/Semana-6.jpg\",\"contentUrl\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/wp-content\\\/uploads\\\/sites\\\/90\\\/2024\\\/04\\\/Semana-6.jpg\",\"width\":1024,\"height\":685},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/2024\\\/04\\\/18\\\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El enoturismo en la 38 Semana de la Empresa de la Facultad de Econom\u00eda de la Universidad de La Laguna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/#website\",\"url\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/\",\"name\":\"Enoturismo Canarias\",\"description\":\"C\u00e1tedra de Agroturismo y Enoturismo Instituto de Canario de Calidad Agroalimentaria\",\"publisher\":{\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/#organization\",\"name\":\"C\u00e1tedra de Agroturismo y Enoturismo de Canarias del Instituto Canario de Calidad Agroalimentaria y de la Universidad de La Laguna\",\"url\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/wp-content\\\/uploads\\\/sites\\\/90\\\/2021\\\/03\\\/Logotipo-Catedra.png\",\"contentUrl\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/wp-content\\\/uploads\\\/sites\\\/90\\\/2021\\\/03\\\/Logotipo-Catedra.png\",\"width\":300,\"height\":89,\"caption\":\"C\u00e1tedra de Agroturismo y Enoturismo de Canarias del Instituto Canario de Calidad Agroalimentaria y de la Universidad de La Laguna\"},\"image\":{\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/enoturismoull\",\"https:\\\/\\\/x.com\\\/enoturismoull\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/40816665\\\/admin\\\/dashboard\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/#\\\/schema\\\/person\\\/08dc3be5406aba55875ae5024a8e7426\",\"name\":\"aenogas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/957f529db4c10409aeb4798f38d978d31a86852b0557feaaa15ada6691fe502f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/957f529db4c10409aeb4798f38d978d31a86852b0557feaaa15ada6691fe502f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/957f529db4c10409aeb4798f38d978d31a86852b0557feaaa15ada6691fe502f?s=96&d=mm&r=g\",\"caption\":\"aenogas\"},\"url\":\"https:\\\/\\\/wp.ull.es\\\/aenogas\\\/author\\\/aenogas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El enoturismo en la 38 Semana de la Empresa de la Facultad de Econom\u00eda de la Universidad de La Laguna - Enoturismo Canarias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/","og_locale":"es_ES","og_type":"article","og_title":"El enoturismo en la 38 Semana de la Empresa de la Facultad de Econom\u00eda de la Universidad de La Laguna - Enoturismo Canarias","og_description":"La C\u00e1tedra de Agroturismo y Enoturismo de Canarias del Instituto Canario de Calidad Agroalimentaria y de la Universidad de La Laguna, particip\u00f3 en la 38 Semana de la Empresa promovida por la Delegaci\u00f3n de Estudiantes, de la Facultad de Econom\u00eda, Empresa y Turismo de la instituci\u00f3n acad\u00e9mica.Leer m\u00e1s \u203a","og_url":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/","og_site_name":"Enoturismo Canarias","article_publisher":"https:\/\/www.facebook.com\/enoturismoull","article_published_time":"2024-04-18T15:29:09+00:00","article_modified_time":"2024-04-18T15:29:11+00:00","og_image":[{"width":1024,"height":685,"url":"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-6.jpg","type":"image\/jpeg"}],"author":"aenogas","twitter_card":"summary_large_image","twitter_creator":"@enoturismoull","twitter_site":"@enoturismoull","twitter_misc":{"Escrito por":"aenogas","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/#article","isPartOf":{"@id":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/"},"author":{"name":"aenogas","@id":"https:\/\/wp.ull.es\/aenogas\/#\/schema\/person\/08dc3be5406aba55875ae5024a8e7426"},"headline":"El enoturismo en la 38 Semana de la Empresa de la Facultad de Econom\u00eda de la Universidad de La Laguna","datePublished":"2024-04-18T15:29:09+00:00","dateModified":"2024-04-18T15:29:11+00:00","mainEntityOfPage":{"@id":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/"},"wordCount":315,"commentCount":0,"publisher":{"@id":"https:\/\/wp.ull.es\/aenogas\/#organization"},"image":{"@id":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/#primaryimage"},"thumbnailUrl":"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-6.jpg","keywords":["enoturismo","universidad de la laguna"],"articleSection":["Blog"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/","url":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/","name":"El enoturismo en la 38 Semana de la Empresa de la Facultad de Econom\u00eda de la Universidad de La Laguna - Enoturismo Canarias","isPartOf":{"@id":"https:\/\/wp.ull.es\/aenogas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/#primaryimage"},"image":{"@id":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/#primaryimage"},"thumbnailUrl":"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-6.jpg","datePublished":"2024-04-18T15:29:09+00:00","dateModified":"2024-04-18T15:29:11+00:00","breadcrumb":{"@id":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/#primaryimage","url":"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-6.jpg","contentUrl":"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2024\/04\/Semana-6.jpg","width":1024,"height":685},{"@type":"BreadcrumbList","@id":"https:\/\/wp.ull.es\/aenogas\/2024\/04\/18\/el-enoturismo-en-la-38-semana-de-la-empresa-de-la-facultad-de-economia-de-la-universidad-de-la-laguna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/wp.ull.es\/aenogas\/"},{"@type":"ListItem","position":2,"name":"El enoturismo en la 38 Semana de la Empresa de la Facultad de Econom\u00eda de la Universidad de La Laguna"}]},{"@type":"WebSite","@id":"https:\/\/wp.ull.es\/aenogas\/#website","url":"https:\/\/wp.ull.es\/aenogas\/","name":"Enoturismo Canarias","description":"C\u00e1tedra de Agroturismo y Enoturismo Instituto de Canario de Calidad Agroalimentaria","publisher":{"@id":"https:\/\/wp.ull.es\/aenogas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.ull.es\/aenogas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/wp.ull.es\/aenogas\/#organization","name":"C\u00e1tedra de Agroturismo y Enoturismo de Canarias del Instituto Canario de Calidad Agroalimentaria y de la Universidad de La Laguna","url":"https:\/\/wp.ull.es\/aenogas\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wp.ull.es\/aenogas\/#\/schema\/logo\/image\/","url":"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2021\/03\/Logotipo-Catedra.png","contentUrl":"https:\/\/wp.ull.es\/aenogas\/wp-content\/uploads\/sites\/90\/2021\/03\/Logotipo-Catedra.png","width":300,"height":89,"caption":"C\u00e1tedra de Agroturismo y Enoturismo de Canarias del Instituto Canario de Calidad Agroalimentaria y de la Universidad de La Laguna"},"image":{"@id":"https:\/\/wp.ull.es\/aenogas\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/enoturismoull","https:\/\/x.com\/enoturismoull","https:\/\/www.linkedin.com\/company\/40816665\/admin\/dashboard\/"]},{"@type":"Person","@id":"https:\/\/wp.ull.es\/aenogas\/#\/schema\/person\/08dc3be5406aba55875ae5024a8e7426","name":"aenogas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/957f529db4c10409aeb4798f38d978d31a86852b0557feaaa15ada6691fe502f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/957f529db4c10409aeb4798f38d978d31a86852b0557feaaa15ada6691fe502f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/957f529db4c10409aeb4798f38d978d31a86852b0557feaaa15ada6691fe502f?s=96&d=mm&r=g","caption":"aenogas"},"url":"https:\/\/wp.ull.es\/aenogas\/author\/aenogas\/"}]}},"_links":{"self":[{"href":"https:\/\/wp.ull.es\/aenogas\/wp-json\/wp\/v2\/posts\/5505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ull.es\/aenogas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ull.es\/aenogas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ull.es\/aenogas\/wp-json\/wp\/v2\/users\/227"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ull.es\/aenogas\/wp-json\/wp\/v2\/comments?post=5505"}],"version-history":[{"count":1,"href":"https:\/\/wp.ull.es\/aenogas\/wp-json\/wp\/v2\/posts\/5505\/revisions"}],"predecessor-version":[{"id":5511,"href":"https:\/\/wp.ull.es\/aenogas\/wp-json\/wp\/v2\/posts\/5505\/revisions\/5511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.ull.es\/aenogas\/wp-json\/wp\/v2\/media\/5506"}],"wp:attachment":[{"href":"https:\/\/wp.ull.es\/aenogas\/wp-json\/wp\/v2\/media?parent=5505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ull.es\/aenogas\/wp-json\/wp\/v2\/categories?post=5505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ull.es\/aenogas\/wp-json\/wp\/v2\/tags?post=5505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}